{"id":2753,"date":"2021-04-19T19:42:12","date_gmt":"2021-04-19T17:42:12","guid":{"rendered":"https:\/\/sehlde.info\/content\/?p=2753"},"modified":"2025-06-16T10:33:52","modified_gmt":"2025-06-16T08:33:52","slug":"notbetreuung-in-den-kitas-der-samtgemeinde","status":"publish","type":"post","link":"https:\/\/sehlde.info\/content\/2021\/04\/notbetreuung-in-den-kitas-der-samtgemeinde\/","title":{"rendered":"Notbetreuung in den Kita&#8217;s der Samtgemeinde"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Schreiben der Samtgemeindeverwaltung an die Ratsmitglieder<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>seit heute ist in den Kindertagest\u00e4tten der Samtgemeinde Baddeckenstedt aufgrund einer Allgemeinverf\u00fcgung des Landkreises Wolfenb\u00fcttel nur eine Notbetreuung m\u00f6glich. Es d\u00fcrfen also nur 50 % der Kinder in den jeweiligen Gruppen betreut werden. Eine Vermischung der Gruppen ist untersagt. Diese Notbetreuung gilt solange, bis der Inzidenzwert im Landkreis an drei folgenden Tagen unter 100 liegt und davon auszugehen ist, dass dieses auch so bleibt. (Aktuell: 135,4)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der Platzvergabe ist die Bed\u00fcrftigkeit der Eltern zu pr\u00fcfen. Insbesondere bei der Ganztagsbetreuung reichen die verf\u00fcgbaren Pl\u00e4tze leider nicht aus, so dass nicht alle W\u00fcnsche ber\u00fccksichtigt werden k\u00f6nnen. Bei der Halbtagsbetreuung sind teilweise noch Pl\u00e4tze verf\u00fcgbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund der personellen Situation kann die Samtgemeinde kein zus\u00e4tzliches Gruppenangebot machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Klaus Kubitschke, B\u00fcrgermeister der Samtgemeinde, hat f\u00fcr den Unmut der Eltern Verst\u00e4ndnis, die keinen Platz f\u00fcr ihr Kind erhalten haben. Leider ist es nicht m\u00f6glich Abhilfe zu schaffen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schreiben der Samtgemeindeverwaltung an die Ratsmitglieder seit heute ist in den Kindertagest\u00e4tten der Samtgemeinde Baddeckenstedt aufgrund einer Allgemeinverf\u00fcgung des Landkreises Wolfenb\u00fcttel nur eine Notbetreuung m\u00f6glich. Es d\u00fcrfen also nur 50 &#8230; <a title=\"Notbetreuung in den Kita&#8217;s der Samtgemeinde\" class=\"read-more\" href=\"https:\/\/sehlde.info\/content\/2021\/04\/notbetreuung-in-den-kitas-der-samtgemeinde\/\" aria-label=\"Mehr Informationen \u00fcber Notbetreuung in den Kita&#8217;s der Samtgemeinde\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,41],"tags":[],"class_list":["post-2753","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-infos"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/posts\/2753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/comments?post=2753"}],"version-history":[{"count":1,"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/posts\/2753\/revisions"}],"predecessor-version":[{"id":2754,"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/posts\/2753\/revisions\/2754"}],"wp:attachment":[{"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/media?parent=2753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/categories?post=2753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sehlde.info\/content\/wp-json\/wp\/v2\/tags?post=2753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}